{"id":1117,"date":"2013-10-21T21:53:30","date_gmt":"2013-10-22T02:53:30","guid":{"rendered":"https:\/\/rafael.bonifaz.ec\/blog\/?p=1117"},"modified":"2017-01-21T10:36:22","modified_gmt":"2017-01-21T13:36:22","slug":"encriptar-correos-con-pgp","status":"publish","type":"post","link":"https:\/\/rafael.bonifaz.ec\/blog\/2013\/10\/encriptar-correos-con-pgp\/","title":{"rendered":"Encriptar Correos con PGP"},"content":{"rendered":"<p><strong>Actualizaci\u00f3n Agosto 2 &#8211; 2015<\/strong><\/p>\n<p>Este art\u00edculo lo escrib\u00ed en octubre de 2013, luego de las revelaciones de Snowden. Es un tutorial para evitar que los correos sean le\u00eddos por terceros. Nos es perfecto, pero incrementar\u00e1 la seguridad de sus comunicaciones notablemente.<\/p>\n<p>Lo hice para Linux, que es lo que uso, sin embargo una ves instalado se lo puede utilizar desde la parte de <strong>configuraci\u00f3n de Gmail<\/strong>. Intento no usar Gmail y no recomiendo su uso. Con pocas modificaciones este tutorial podr\u00eda funcionar para herramientas como Hotmail, Yahoo, o cualquir correo que soporte los protocolos IMAP o POP3.<\/p>\n<p>Para instalar las herramientas en Windows o Mac pueden complementar este tutorial con el que hizo la Free Software Foundation: <strong>\u00ab<a href=\"https:\/\/emailselfdefense.fsf.org\/es\/\" target=\"_blank\">Defensa personal del correo electr\u00f3nico<\/a>\u00ab<\/strong>.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>A muchas personas les preocupa el tema del espionaje y no saben como defenderse. En un art\u00edculo anterior <a title=\"Chat Encriptado con Pidgin y OTR\" href=\"https:\/\/rafael.bonifaz.ec\/blog\/2013\/03\/chat-encriptado-con-pidgin-y-otr\/\">expliqu\u00e9 como proteger las comunicaciones por chat<\/a>. En este art\u00edculo explicare como proteger los correos electr\u00f3nicos de un correo ya existente. Para este ejemplo utilizar\u00e9 una cuenta de Gmail, pero el mismo concepto funcionar\u00e1 para Yahoo, Hotmail y correos propios (lo ideal) que no dependan de estas corporaciones.<\/p>\n<p>Es importante notar que si bien se pueden cifrar los correos de servicios como Gmail, no es lo m\u00e1s conveniente. Ellos siguen teniendo nuestros correos y tal vez en el futuro los puedan descifrar y adem\u00e1s tienen nuestra metadata. Es decir con qui\u00e9n me comunico, con que frecuencia, desde donde, etc&#8230;. Este tutorial deber\u00eda servir como un primer paso para tener privacidad. El siguiente paso ser\u00eda conseguir un servidor de correo propio para una organizaci\u00f3n, comunidad, amigos, etc&#8230;.<!--more--><\/p>\n<h2>Instalar Thunderbird\/Icedove y Enigmail<\/h2>\n<p>Si usan Windows o Mac deber\u00e1n buscar como instalar los programas <a href=\"https:\/\/www.mozilla.org\/es-AR\/thunderbird\/\" target=\"_blank\">Thunderbird<\/a>, <a href=\"https:\/\/addons.mozilla.org\/en-US\/thunderbird\/addon\/enigmail\/\" target=\"_blank\">Enigmail<\/a> y <a href=\"http:\/\/gnupg.org\/download\/index.en.html\" target=\"_blank\">GPG<\/a>. En el caso de GNU\/Linux, GPG ya viene instalado y muchas veces Thunderbird.<\/p>\n<p>En distribuciones como Ubuntu, Linux Mint se pueden instalar los paquetes necesarios de la siguiente manera:<\/p>\n<p><code>sudo apt-get install thunderbird enigmail thunderbird-l10n-es-ar<\/code><\/p>\n<p>En el caso de Debian el paquete se llama icedove en lugar de thunderbird, por temas relacionados con marcas.<\/p>\n<p><code>sudo apt-get install icedove enigmail icedove-l10n-es-ar<\/code><\/p>\n<p>En el caso de otras distribuciones se instalar\u00e1 los paquetes correspondientes.<\/p>\n<h2>Configurar Gmail con IMAP en Thunderbird<\/h2>\n<p>Una vez configurado instalado Thunderbird con Enigmail, el siguiente paso es configurarlo con nuestra cuenta de correo electr\u00f3nico. Para este ejemplo utilizar\u00e1 Gmail, que como ya dije antes, no es lo mejor pero es un avance importante si se quiere tener privacidad.<\/p>\n<p>Lo primero que decimos es que no queremos crear una cuenta sino utilizar una existente<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_060.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1118\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_060.png\" alt=\"Thunderbird Gmail 1\" width=\"632\" height=\"475\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_060.png 632w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_060-300x225.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_060-399x300.png 399w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/a><\/p>\n<p>Configuramos los datos de la cuenta de Gmail:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_061.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1119\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_061.png\" alt=\"Thunderbird Gmail 2\" width=\"679\" height=\"462\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_061.png 679w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_061-300x204.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_061-440x300.png 440w\" sizes=\"auto, (max-width: 679px) 100vw, 679px\" \/><\/a><\/p>\n<p>Luego de dar click en continuar Thunderbird \/ Icedove har\u00e1 las comprobaciones de la cuenta y configurar\u00e1 IMAP:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_062.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1121\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_062.png\" alt=\"Thunderbird Gmail 3\" width=\"673\" height=\"461\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_062.png 673w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_062-300x205.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_062-437x300.png 437w\" sizes=\"auto, (max-width: 673px) 100vw, 673px\" \/><\/a><\/p>\n<p>Listo se ha configurado la cuenta y se empezar\u00e1 a descargar los correos de Gmail.<\/p>\n<h2>Llaves P\u00fablicas y Privadas<\/h2>\n<p>El concepto de criptograf\u00eda cuando se utiliza PGP es el de llaves p\u00fablicas y privadas. Se tiene una llave p\u00fablica que se la entrega a las personas que van a encriptar los correos que voy a recibir. Es m\u00e1s se la puede subir a Internet para que sea m\u00e1s f\u00e1cil para otros cifrarme los correos. Por otro lado se tiene la llave privada que sirve para descifrar los correos. Esta llave no se debe compartir y es recomendable sacar un respaldo ya que sin esta no se podr\u00e1n leer los correos.<\/p>\n<p>Las llave privada tambi\u00e9n sirve para firmar los correos electr\u00f3nicos y la p\u00fablica para verificar si la firma de los correos es correcta. Es decir PGP tambi\u00e9n funciona para tener firma digital.<\/p>\n<h2>Crear par de Llaves P\u00fablicas y Privadas<\/h2>\n<p>Es muy probable que la instalaci\u00f3n de Thunderbird \/ Icedove tenga el problema de que no sean visibles los men\u00fas. Para esto configuramos con click derecho en la parte superior para que estos sean visibles.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_065.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1122\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_065.png\" alt=\"Thunderbird ver men\u00fas \" width=\"528\" height=\"109\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_065.png 528w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_065-300x61.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_065-500x103.png 500w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/a><\/p>\n<p>Una vez que es visible el men\u00fa, se selecciona el men\u00fa OpenPGP y luego el <em>administrador de claves<\/em>:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_068.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1123\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_068.png\" alt=\"generar llaves 1\" width=\"434\" height=\"242\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_068.png 434w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_068-300x167.png 300w\" sizes=\"auto, (max-width: 434px) 100vw, 434px\" \/><\/a><\/p>\n<p>En el administrador de claves seleccionamos <em>Generar<\/em> -&gt; <em>Nuevo par de claves<\/em><\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_069.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1124\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_069.png\" alt=\"generar llaves 2\" width=\"639\" height=\"126\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_069.png 639w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_069-300x59.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_069-500x98.png 500w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/a><\/p>\n<p>Asignamos una contrase\u00f1a y de manera opcional un comentario para la llave p\u00fablica. El comentario podr\u00eda ser mi nombre y algo que me describa. Se define si se le da opci\u00f3n de caducidad al par de llaves. Es recomendable dar un tiempo de vida a nuestras llaves e ir renovando cada cierto tiempo.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_070.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1125\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_070.png\" alt=\"generar llaves 3\" width=\"649\" height=\"368\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_070.png 649w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_070-300x170.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_070-500x283.png 500w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/a><\/p>\n<p>En la misma venta seleccionamos la opci\u00f3n de avanzados para seleccionar el tama\u00f1o de llaves m\u00e1s grande permitido. En este caso el valor es 4096:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_071.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1126\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_071.png\" alt=\"generar llaves 4\" width=\"658\" height=\"382\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_071.png 658w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_071-300x174.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_071-500x290.png 500w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><\/a><\/p>\n<p>Con esto estamos listos para generar el par de llaves p\u00fablicas y privadas. Dependiendo de la computadora esto podr\u00eda tomar alg\u00fan tiempo. Durante el proceso de creaci\u00f3n se nos pregunta si queremos generar un certificado de revocaci\u00f3n de la llave p\u00fablica. Esto es \u00fatil si se tiene la llave subida a un servidor y por alg\u00fan motivo ya no se la quiere utilizar. Por ejemplo, mi computadora fue robada. Es recomendable generar el certificado y guardarlo en alg\u00fan lugar seguro:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_073.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1127\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_073.png\" alt=\"generar llaves 5\" width=\"716\" height=\"176\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_073.png 716w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_073-300x73.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_073-500x122.png 500w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/a><\/p>\n<h2>Importar una llave p\u00fablica y enviar el primer correo cifrado<\/h2>\n<p>Lo primero que debemos hacer para enviar un correo cifrado a alguien es solicitar su llave p\u00fablica. Una forma sencilla de recibirla puede ser a trav\u00e9s de correo electr\u00f3nico como adjunto. Luego desde el administrador de claves la podemos importar.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_079.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1129\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_079.png\" alt=\"importar clave 1\" width=\"639\" height=\"327\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_079.png 639w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_079-300x153.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_079-500x255.png 500w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/a><\/p>\n<p>Luego buscamos el archivo con la llave p\u00fablica y lo importamos.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_080.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1130\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_080.png\" alt=\"Importar clave 2\" width=\"618\" height=\"250\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_080.png 618w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_080-300x121.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_080-500x202.png 500w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/a><\/p>\n<p>Con esto ya estamos listos para enviar nuestro primer correo cifrado. B\u00e1sicamente en el bot\u00f3n de OpenPGP habilitamos la opci\u00f3n de cifrar el correo.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_078.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1131\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_078.png\" alt=\"Enviar correo cifrado\" width=\"671\" height=\"369\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_078.png 671w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_078-300x164.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_078-500x274.png 500w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/a><\/p>\n<p>Listo ya hemos enviado nuestro primer correo cifrado.<\/p>\n<h1>Compartir Nuestra Llave P\u00fablica<\/h1>\n<p>Ahora que ya podemos enviar correos cifrados, es importante que podamos recibir correos cifrados. Para esto debemos hacer accesible nuestra llave p\u00fablica. Una forma es a trav\u00e9s de correo electr\u00f3nico. En el men\u00fa de redacci\u00f3n de correo existe la opci\u00f3n <em>OpenPGP<\/em> -&gt; <em>Adjuntar mi clave p\u00fablica<\/em>.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_081.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1132\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_081.png\" alt=\"adjuntar llave p\u00fablica\" width=\"347\" height=\"432\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_081.png 347w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_081-240x300.png 240w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\" \/><\/a><\/p>\n<p>Otra opci\u00f3n es subir la llave p\u00fablica a los servidores de Internet y hacerla accesible a m\u00e1s gente. De esta manera m\u00e1s personas se podr\u00e1n cifrarme correos electr\u00f3nicos.<br \/>\nPara esto en el administrador de claves, buscamos la clave (por nombre, por ejemplo) y la exportamos a los servidores p\u00fablicos.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_083.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1133\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_083.png\" alt=\"exportar clave\" width=\"884\" height=\"394\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_083.png 884w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_083-300x133.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_083-500x222.png 500w\" sizes=\"auto, (max-width: 884px) 100vw, 884px\" \/><\/a><\/p>\n<h2>Verificar la clave<\/h2>\n<p>Es importante verificar que la llave p\u00fablica corresponde a la persona con la que me quiero comunicar. No quisiera enviar un correo cifrado que lo lea otra persona. Para esto debemos comprobar la llave p\u00fablica y esto se lo hace a trav\u00e9s del ID o el Finger Print.<\/p>\n<p>Para conocer el ID o el Finger print de la llave p\u00fablica, en el administrador de claves se selecciona la clave y se pone las propiedades de la misma.<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_084.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1134\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_084.png\" alt=\"propiedades clave\" width=\"712\" height=\"401\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_084.png 712w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_084-300x168.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_084-500x281.png 500w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/><\/a><\/p>\n<p>Personalmente casi no uso Gmail y lo use para este ejemplo. Sin embargo para mi cuenta de correo electr\u00f3nico convencional se puede ver los datos de mi clave p\u00fablica en la siguiente diapositiva:<\/p>\n<p><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_085.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1135\" src=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_085.png\" alt=\"Rafael Bonifaz llave p\u00fablica pgp\" width=\"844\" height=\"545\" srcset=\"https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_085.png 844w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_085-300x193.png 300w, https:\/\/rafael.bonifaz.ec\/blog\/wp-content\/uploads\/2013\/10\/Selecci\u00f3n_085-464x300.png 464w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\" \/><\/a><\/p>\n<p>Si quieren practicar enviar un correo electr\u00f3nico, pueden utilizar <a href=\"https:\/\/sks-keyservers.net\/pks\/lookup?op=get&amp;search=0xCDFE573165138A9F\">mi llave p\u00fablica<\/a>.<\/p>\n<p>Este fue un peque\u00f1o tutorial para empezar a cifrar correos electr\u00f3nicos. Hay muchas otras cosas que se pueden hacer con PGP, pero esto es lo b\u00e1sico que deber\u00edamos utilizar.<\/p>\n<h3 class='related_post_title'>Art\u00edculos relacionados<\/h3><ul class='related_post'><li><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/2013\/03\/software-libre-criptografia-y-privacidad\/\" title=\"Software Libre, Criptograf\u00eda y Privacidad\">Software Libre, Criptograf\u00eda y Privacidad<\/a><\/li><li><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/2017\/01\/el-2017-todos-a-encriptar\/\" title=\"\u00a1El 2017 todos a encriptar!\">\u00a1El 2017 todos a encriptar!<\/a><\/li><li><a href=\"https:\/\/rafael.bonifaz.ec\/blog\/2014\/10\/el-espionaje-informatico-y-el-rol-de-los-medios-de-comunicacion\/\" title=\"El Espionaje Inform\u00e1tico y el rol de los Medios de Comunicaci\u00f3n\">El Espionaje Inform\u00e1tico y el rol de los Medios de Comunicaci\u00f3n<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Actualizaci\u00f3n Agosto 2 &#8211; 2015 Este art\u00edculo lo escrib\u00ed en octubre de 2013, luego de las revelaciones de Snowden. Es un tutorial para evitar que los correos sean le\u00eddos por terceros. Nos es perfecto, pero incrementar\u00e1 la seguridad de sus comunicaciones notablemente. Lo hice para Linux, que es lo que uso, sin embargo una ves [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[10,70,1,3],"tags":[174,178,138,162,139,181,172,161],"class_list":["post-1117","post","type-post","status-publish","format-standard","hentry","category-asle","category-comos","category-general","category-software-libre","tag-asle","tag-comos","tag-enigmail","tag-icedove","tag-pgp","tag-privacidad","tag-software-libre","tag-thunderbird"],"_links":{"self":[{"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/posts\/1117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/comments?post=1117"}],"version-history":[{"count":7,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/posts\/1117\/revisions"}],"predecessor-version":[{"id":4751,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/posts\/1117\/revisions\/4751"}],"wp:attachment":[{"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/media?parent=1117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/categories?post=1117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rafael.bonifaz.ec\/blog\/wp-json\/wp\/v2\/tags?post=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}